{"id":1708,"date":"2020-04-29T19:48:52","date_gmt":"2020-04-29T17:48:52","guid":{"rendered":"http:\/\/alice-corporation.com\/vegetal\/?p=1708"},"modified":"2020-04-29T19:49:19","modified_gmt":"2020-04-29T17:49:19","slug":"1708","status":"publish","type":"post","link":"https:\/\/alice-corporation.com\/vegetal\/1708\/","title":{"rendered":"1 mois de printemps plus tard&#8230;"},"content":{"rendered":"<p>Quoi de neuf ?<\/p>\n<p>Les plants de tomates ont bien pouss\u00e9, mi mai je les mettrais en pot (pots qui ont \u00e9t\u00e9 nettoy\u00e9s, ouaiiiis). Quand je pense qu&rsquo;une partie de mes graines ont 5 ans minimum et qu&rsquo;elles germent toujours aussi bien (100% de lev\u00e9e !). J&rsquo;ai aussi sem\u00e9 des Suzannes aux yeux noirs, qui ne sont pas sorties du tout. Je refais un essai apr\u00e8s avoir fait tremper les graines 24h pour voir. J&rsquo;ai sem\u00e9 de la ciboulette, des radis (qui ont commenc\u00e9 \u00e0 sortir leurs petites feuilles en forme de c\u0153ur !) et des cob\u00e9es qui sont bien parties elles aussi ! Je pr\u00e9vois de diviser\/rempoter Mr Bananier dans un pot un peu plus grand (en esp\u00e9rant r\u00e9ussir \u00e0 le d\u00e9barrasser de ses cochenilles au passage)<\/p>\n<p>J&rsquo;ai d\u00e9cid\u00e9 de recycler un reste de poudre d&rsquo;ortie en purin, soyons folle. De ce que j&rsquo;ai compris, au bout de 24h, on peut l&rsquo;utiliser comme insecticide et vu que les cochenilles et pucerons sont toujours de la partie, ma foi, testons ! J&rsquo;en ai filtr\u00e9 1l au bout de 24h donc et le reste est toujours dans son bidon, \u00e0 fermenter. Rdv dans 2 semaines !<\/p>\n<p>Cette ann\u00e9e, pas d&rsquo;iris semble-t-il, m\u00eame si les feuilles sont sorties. Pas de muguet non plus, une fois de plus les bulbes sont morts ! Les fraisiers plant\u00e9s il y a quelques semaines ont l&rsquo;air de bien s&rsquo;installer, ils font de nouvelles feuilles, fleurs et se dressent fi\u00e8rement sur leurs petites racines ! Les cl\u00e9matites sont en train d&rsquo;envahir la rambarde.. Plusieurs bourgeons en pr\u00e9paration ! Idem pour les vieux lys, fid\u00e8les au poste ! Les nouveaux par contre&#8230; Pas tr\u00e8s glorieux, on verra l&rsquo;ann\u00e9e prochaine peut-\u00eatre. Mon bambou sacr\u00e9 a pass\u00e9 l&rsquo;arme \u00e0 gauche. C&rsquo;est fou, tout ce qui est arbuste je n&rsquo;y arrive pas !!! Un des agrumes est dead aussi, le second repart. Curieusement, c&rsquo;est celui qui a pass\u00e9 l&rsquo;hiver \u00e0 poil qui s&rsquo;en sort.<\/p>\n<p>Il faut que je trouve de quoi remplacer les ch\u00e8vrefeuilles. Un truc genre intuable, qui supporte l&rsquo;exposition NO et persistant. Je trouve \u00e7a moche mais j&rsquo;envisage du buis. Sachant que je convoite aussi Oranger du Mexique, Deutzia gracilis et Camellia Fairy Wand. Rien que \u00e7a.<\/p>\n<p>&nbsp;<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-1708 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/alice-corporation.com\/vegetal\/1708\/18042020-_dsc8305-copier\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/alice-corporation.com\/vegetal\/wp-content\/uploads\/2020\/04\/18042020-_DSC8305-Copier-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-1712\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-1712'>\n\t\t\t\tCampanule, toujours plaisant et facile..\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/alice-corporation.com\/vegetal\/1708\/18042020-_dsc8308-copier\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/alice-corporation.com\/vegetal\/wp-content\/uploads\/2020\/04\/18042020-_DSC8308-Copier-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-1713\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-1713'>\n\t\t\t\tCoeur de Marie qui ressort encore et toujours.. Il a des ancolies comme colocataires.\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/alice-corporation.com\/vegetal\/1708\/18042020-_dsc8321-copier\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/alice-corporation.com\/vegetal\/wp-content\/uploads\/2020\/04\/18042020-_DSC8321-Copier-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-1714\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-1714'>\n\t\t\t\tVoisin d&rsquo;en face, pigeonne qui couve.\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/alice-corporation.com\/vegetal\/1708\/18042020-_dsc8333-copier\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/alice-corporation.com\/vegetal\/wp-content\/uploads\/2020\/04\/18042020-_DSC8333-Copier-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-1715\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-1715'>\n\t\t\t\tFleurs de fraisier\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/alice-corporation.com\/vegetal\/1708\/18042020-_dsc8346-copier\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/alice-corporation.com\/vegetal\/wp-content\/uploads\/2020\/04\/18042020-_DSC8346-Copier-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-1716\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-1716'>\n\t\t\t\tFleur de b\u00e9gonia\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/alice-corporation.com\/vegetal\/1708\/_dsc8289-copier\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/alice-corporation.com\/vegetal\/wp-content\/uploads\/2020\/04\/DSC8289-Copier-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-1717\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-1717'>\n\t\t\t\tLes tulipes !\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/alice-corporation.com\/vegetal\/1708\/25042020-_dsc8362-copier\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/alice-corporation.com\/vegetal\/wp-content\/uploads\/2020\/04\/25042020-_DSC8362-Copier-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-1719\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-1719'>\n\t\t\t\tFleur du fuschia rampant, il est rest\u00e9 vert tout l&rsquo;hiver. On dirait que rien ne l&rsquo;atteint !\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/alice-corporation.com\/vegetal\/1708\/27042020-_dsc8371-copier\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/alice-corporation.com\/vegetal\/wp-content\/uploads\/2020\/04\/27042020-_DSC8371-Copier-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-1709\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-1709'>\n\t\t\t\tCuriosit\u00e9 sur le Magic Art.\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/alice-corporation.com\/vegetal\/1708\/27042020-_dsc8374-copier\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/alice-corporation.com\/vegetal\/wp-content\/uploads\/2020\/04\/27042020-_DSC8374-Copier-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-1710\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-1710'>\n\t\t\t\tJ&rsquo;ai v\u00e9rifi\u00e9, aucun des parents n&rsquo;a cette forme ni cette couleur. Ca semble pourtant \u00eatre un ph\u00e9nom\u00e8ne fr\u00e9quent.\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/alice-corporation.com\/vegetal\/1708\/23042020-_dsc8351-copier\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/alice-corporation.com\/vegetal\/wp-content\/uploads\/2020\/04\/23042020-_DSC8351-Copier-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-1711\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-1711'>\n\t\t\t\tLes 3 grosses ensemble.. En fleurs depuis janvier !!! Les fleurs de la blanche commencent \u00e0 peine \u00e0 faner (certainement \u00e0 cause des violences subies pour cette photo)\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/alice-corporation.com\/vegetal\/1708\/_dsc8376-copier\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/alice-corporation.com\/vegetal\/wp-content\/uploads\/2020\/04\/DSC8376-Copier-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-1718\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-1718'>\n\t\t\t\tA gauche Fred, \u00e0 droite Clowesia. Cette ann\u00e9e, j&rsquo;essaye d&rsquo;y faire vraiment attention !\n\t\t\t\t<\/dd><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Quoi de neuf ? Les plants de tomates ont bien pouss\u00e9, mi mai je les mettrais en pot (pots qui ont \u00e9t\u00e9 nettoy\u00e9s, ouaiiiis). Quand je pense qu&rsquo;une partie de mes graines ont 5 ans minimum et qu&rsquo;elles germent toujours aussi bien (100% de lev\u00e9e !). J&rsquo;ai aussi sem\u00e9 des Suzannes aux yeux noirs, qui [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[26,25,24,17,35,14],"_links":{"self":[{"href":"https:\/\/alice-corporation.com\/vegetal\/wp-json\/wp\/v2\/posts\/1708"}],"collection":[{"href":"https:\/\/alice-corporation.com\/vegetal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alice-corporation.com\/vegetal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alice-corporation.com\/vegetal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alice-corporation.com\/vegetal\/wp-json\/wp\/v2\/comments?post=1708"}],"version-history":[{"count":2,"href":"https:\/\/alice-corporation.com\/vegetal\/wp-json\/wp\/v2\/posts\/1708\/revisions"}],"predecessor-version":[{"id":1721,"href":"https:\/\/alice-corporation.com\/vegetal\/wp-json\/wp\/v2\/posts\/1708\/revisions\/1721"}],"wp:attachment":[{"href":"https:\/\/alice-corporation.com\/vegetal\/wp-json\/wp\/v2\/media?parent=1708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alice-corporation.com\/vegetal\/wp-json\/wp\/v2\/categories?post=1708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alice-corporation.com\/vegetal\/wp-json\/wp\/v2\/tags?post=1708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}